{"id":314,"date":"2017-09-19T09:39:01","date_gmt":"2017-09-19T08:39:01","guid":{"rendered":"http:\/\/www.apafacadesystems.com\/staging\/?post_type=portfolio&#038;p=314"},"modified":"2020-07-31T13:11:14","modified_gmt":"2020-07-31T12:11:14","slug":"the-bergeron-centre-york-university","status":"publish","type":"portfolio","link":"http:\/\/www.apafacadesystems.com\/staging\/portfolio\/the-bergeron-centre-york-university\/","title":{"rendered":"The Bergeron Centre For Engineering Excellence, York University, Canada"},"content":{"rendered":"","protected":false},"featured_media":4462,"template":"","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false},"portfolio-categories":[24],"class_list":["post-314","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-categories-display-in-listing"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Bergeron Centre, York University- APA Facade Systems<\/title>\n<meta name=\"description\" content=\"APA Facade Systems provided our TB50 SG System for this beautiful building in the York University, the Bergeron Centre for Engineering Excellence.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.apafacadesystems.com\/staging\/portfolio\/the-bergeron-centre-york-university\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Bergeron Centre, York University- APA Facade Systems\" \/>\n<meta property=\"og:description\" content=\"APA Facade Systems provided our TB50 SG System for this beautiful building in the York University, the Bergeron Centre for Engineering Excellence.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.apafacadesystems.com\/staging\/portfolio\/the-bergeron-centre-york-university\/\" \/>\n<meta property=\"og:site_name\" content=\"Staging\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-31T12:11:14+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.apafacadesystems.com\/staging\/wp-content\/uploads\/sites\/7\/2017\/09\/Bergeron-low-res-Double-Space-e1558623444802.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"464\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/portfolio\\\/the-bergeron-centre-york-university\\\/\",\"url\":\"http:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/portfolio\\\/the-bergeron-centre-york-university\\\/\",\"name\":\"The Bergeron Centre, York University- APA Facade Systems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/portfolio\\\/the-bergeron-centre-york-university\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/portfolio\\\/the-bergeron-centre-york-university\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/09\\\/Bergeron-low-res-Double-Space-e1558623444802.png\",\"datePublished\":\"2017-09-19T08:39:01+00:00\",\"dateModified\":\"2020-07-31T12:11:14+00:00\",\"description\":\"APA Facade Systems provided our TB50 SG System for this beautiful building in the York University, the Bergeron Centre for Engineering Excellence.\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/portfolio\\\/the-bergeron-centre-york-university\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/portfolio\\\/the-bergeron-centre-york-university\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"http:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/portfolio\\\/the-bergeron-centre-york-university\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/09\\\/Bergeron-low-res-Double-Space-e1558623444802.png\",\"contentUrl\":\"http:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/09\\\/Bergeron-low-res-Double-Space-e1558623444802.png\",\"width\":700,\"height\":464,\"caption\":\"The Bergeron Center York University\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/portfolio\\\/the-bergeron-centre-york-university\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"http:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/portfolio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"The Bergeron Centre For Engineering Excellence, York University, Canada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/#website\",\"url\":\"https:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/\",\"name\":\"Staging\",\"description\":\"Turning Architectural Design In To Reality\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/#organization\",\"name\":\"Staging\",\"url\":\"https:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/10\\\/logo-red.png\",\"contentUrl\":\"http:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/10\\\/logo-red.png\",\"width\":349,\"height\":171,\"caption\":\"Staging\"},\"image\":{\"@id\":\"https:\\\/\\\/www.apafacadesystems.com\\\/staging\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Bergeron Centre, York University- APA Facade Systems","description":"APA Facade Systems provided our TB50 SG System for this beautiful building in the York University, the Bergeron Centre for Engineering Excellence.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.apafacadesystems.com\/staging\/portfolio\/the-bergeron-centre-york-university\/","og_locale":"en_GB","og_type":"article","og_title":"The Bergeron Centre, York University- APA Facade Systems","og_description":"APA Facade Systems provided our TB50 SG System for this beautiful building in the York University, the Bergeron Centre for Engineering Excellence.","og_url":"http:\/\/www.apafacadesystems.com\/staging\/portfolio\/the-bergeron-centre-york-university\/","og_site_name":"Staging","article_modified_time":"2020-07-31T12:11:14+00:00","og_image":[{"width":700,"height":464,"url":"http:\/\/www.apafacadesystems.com\/staging\/wp-content\/uploads\/sites\/7\/2017\/09\/Bergeron-low-res-Double-Space-e1558623444802.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.apafacadesystems.com\/staging\/portfolio\/the-bergeron-centre-york-university\/","url":"http:\/\/www.apafacadesystems.com\/staging\/portfolio\/the-bergeron-centre-york-university\/","name":"The Bergeron Centre, York University- APA Facade Systems","isPartOf":{"@id":"https:\/\/www.apafacadesystems.com\/staging\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.apafacadesystems.com\/staging\/portfolio\/the-bergeron-centre-york-university\/#primaryimage"},"image":{"@id":"http:\/\/www.apafacadesystems.com\/staging\/portfolio\/the-bergeron-centre-york-university\/#primaryimage"},"thumbnailUrl":"http:\/\/www.apafacadesystems.com\/staging\/wp-content\/uploads\/sites\/7\/2017\/09\/Bergeron-low-res-Double-Space-e1558623444802.png","datePublished":"2017-09-19T08:39:01+00:00","dateModified":"2020-07-31T12:11:14+00:00","description":"APA Facade Systems provided our TB50 SG System for this beautiful building in the York University, the Bergeron Centre for Engineering Excellence.","breadcrumb":{"@id":"http:\/\/www.apafacadesystems.com\/staging\/portfolio\/the-bergeron-centre-york-university\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.apafacadesystems.com\/staging\/portfolio\/the-bergeron-centre-york-university\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"http:\/\/www.apafacadesystems.com\/staging\/portfolio\/the-bergeron-centre-york-university\/#primaryimage","url":"http:\/\/www.apafacadesystems.com\/staging\/wp-content\/uploads\/sites\/7\/2017\/09\/Bergeron-low-res-Double-Space-e1558623444802.png","contentUrl":"http:\/\/www.apafacadesystems.com\/staging\/wp-content\/uploads\/sites\/7\/2017\/09\/Bergeron-low-res-Double-Space-e1558623444802.png","width":700,"height":464,"caption":"The Bergeron Center York University"},{"@type":"BreadcrumbList","@id":"http:\/\/www.apafacadesystems.com\/staging\/portfolio\/the-bergeron-centre-york-university\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.apafacadesystems.com\/staging\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"http:\/\/www.apafacadesystems.com\/staging\/portfolio\/"},{"@type":"ListItem","position":3,"name":"The Bergeron Centre For Engineering Excellence, York University, Canada"}]},{"@type":"WebSite","@id":"https:\/\/www.apafacadesystems.com\/staging\/#website","url":"https:\/\/www.apafacadesystems.com\/staging\/","name":"Staging","description":"Turning Architectural Design In To Reality","publisher":{"@id":"https:\/\/www.apafacadesystems.com\/staging\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.apafacadesystems.com\/staging\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.apafacadesystems.com\/staging\/#organization","name":"Staging","url":"https:\/\/www.apafacadesystems.com\/staging\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.apafacadesystems.com\/staging\/#\/schema\/logo\/image\/","url":"http:\/\/www.apafacadesystems.com\/staging\/wp-content\/uploads\/sites\/7\/2024\/10\/logo-red.png","contentUrl":"http:\/\/www.apafacadesystems.com\/staging\/wp-content\/uploads\/sites\/7\/2024\/10\/logo-red.png","width":349,"height":171,"caption":"Staging"},"image":{"@id":"https:\/\/www.apafacadesystems.com\/staging\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"http:\/\/www.apafacadesystems.com\/staging\/wp-json\/wp\/v2\/portfolio\/314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apafacadesystems.com\/staging\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"http:\/\/www.apafacadesystems.com\/staging\/wp-json\/wp\/v2\/types\/portfolio"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.apafacadesystems.com\/staging\/wp-json\/wp\/v2\/media\/4462"}],"wp:attachment":[{"href":"http:\/\/www.apafacadesystems.com\/staging\/wp-json\/wp\/v2\/media?parent=314"}],"wp:term":[{"taxonomy":"portfolio-categories","embeddable":true,"href":"http:\/\/www.apafacadesystems.com\/staging\/wp-json\/wp\/v2\/portfolio-categories?post=314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}